{"id":1245,"count":1,"description":"Metal Palette","link":"https:\/\/artvallarta.com\/es\/product-category\/art-supplies\/palette\/metal-palette\/","name":"Metal Palette","slug":"metal-palette","taxonomy":"product_cat","parent":96,"meta":[],"menu_order":133,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Metal Palette Archives - Art VallARTa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/artvallarta.com\/es\/product-category\/art-supplies\/palette\/metal-palette\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Metal Palette Archives - Art VallARTa\" \/>\n<meta property=\"og:description\" content=\"Metal Palette\" \/>\n<meta property=\"og:url\" content=\"https:\/\/artvallarta.com\/es\/product-category\/art-supplies\/palette\/metal-palette\/\" \/>\n<meta property=\"og:site_name\" content=\"Art VallARTa\" \/>\n<meta property=\"og:image\" content=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2020\/07\/cropped-51835738_615449708895218_133232196214325248_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"167\" \/>\n\t<meta property=\"og:image:height\" content=\"119\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/product-category\\\/art-supplies\\\/palette\\\/metal-palette\\\/\",\"url\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/product-category\\\/art-supplies\\\/palette\\\/metal-palette\\\/\",\"name\":\"Metal Palette Archives - Art VallARTa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/product-category\\\/art-supplies\\\/palette\\\/metal-palette\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/product-category\\\/art-supplies\\\/palette\\\/metal-palette\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagina principal\",\"item\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/art-vallarta-puerto-vallarta-mexico-home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Suministros de arte\",\"item\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/product-category\\\/art-supplies-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Godetes\",\"item\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/product-category\\\/art-supplies-es\\\/palette-es\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Metal Palette\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/\",\"name\":\"Art VallARTa\",\"description\":\"Art VallARTa\",\"publisher\":{\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/#organization\",\"name\":\"Art VallARTa\",\"url\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/artvallarta.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/51835738_615449708895218_133232196214325248_n.jpg\",\"contentUrl\":\"https:\\\/\\\/artvallarta.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/51835738_615449708895218_133232196214325248_n.jpg\",\"width\":2048,\"height\":1466,\"caption\":\"Art VallARTa\"},\"image\":{\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/artvallarta\",\"http:\\\/\\\/www.instagram.com\\\/artvallarta\",\"http:\\\/\\\/www.pinterest\\\/artvallarta\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCOqDy2Oyk7EU4tz3S2Gl7kQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Metal Palette Archives - Art VallARTa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/artvallarta.com\/es\/product-category\/art-supplies\/palette\/metal-palette\/","og_locale":"es_ES","og_type":"article","og_title":"Metal Palette Archives - Art VallARTa","og_description":"Metal Palette","og_url":"https:\/\/artvallarta.com\/es\/product-category\/art-supplies\/palette\/metal-palette\/","og_site_name":"Art VallARTa","og_image":[{"width":167,"height":119,"url":"https:\/\/artvallarta.com\/wp-content\/uploads\/2020\/07\/cropped-51835738_615449708895218_133232196214325248_n.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/artvallarta.com\/es\/product-category\/art-supplies\/palette\/metal-palette\/","url":"https:\/\/artvallarta.com\/es\/product-category\/art-supplies\/palette\/metal-palette\/","name":"Metal Palette Archives - Art VallARTa","isPartOf":{"@id":"https:\/\/artvallarta.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/artvallarta.com\/es\/product-category\/art-supplies\/palette\/metal-palette\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/artvallarta.com\/es\/product-category\/art-supplies\/palette\/metal-palette\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagina principal","item":"https:\/\/artvallarta.com\/es\/art-vallarta-puerto-vallarta-mexico-home\/"},{"@type":"ListItem","position":2,"name":"Suministros de arte","item":"https:\/\/artvallarta.com\/es\/product-category\/art-supplies-es\/"},{"@type":"ListItem","position":3,"name":"Godetes","item":"https:\/\/artvallarta.com\/es\/product-category\/art-supplies-es\/palette-es\/"},{"@type":"ListItem","position":4,"name":"Metal Palette"}]},{"@type":"WebSite","@id":"https:\/\/artvallarta.com\/es\/#website","url":"https:\/\/artvallarta.com\/es\/","name":"Art VallARTa","description":"Art VallARTa","publisher":{"@id":"https:\/\/artvallarta.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/artvallarta.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/artvallarta.com\/es\/#organization","name":"Art VallARTa","url":"https:\/\/artvallarta.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/artvallarta.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/02\/51835738_615449708895218_133232196214325248_n.jpg","contentUrl":"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/02\/51835738_615449708895218_133232196214325248_n.jpg","width":2048,"height":1466,"caption":"Art VallARTa"},"image":{"@id":"https:\/\/artvallarta.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/artvallarta","http:\/\/www.instagram.com\/artvallarta","http:\/\/www.pinterest\/artvallarta","https:\/\/www.youtube.com\/channel\/UCOqDy2Oyk7EU4tz3S2Gl7kQ"]}]}},"cat_url":"https:\/\/artvallarta.com\/es\/product-category\/art-supplies\/palette\/metal-palette\/","_links":{"self":[{"href":"https:\/\/artvallarta.com\/es\/wp-json\/wp\/v2\/product_cat\/1245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artvallarta.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/artvallarta.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/artvallarta.com\/es\/wp-json\/wp\/v2\/product_cat\/96"}],"wp:post_type":[{"href":"https:\/\/artvallarta.com\/es\/wp-json\/wp\/v2\/product?product_cat=1245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}