{"id":49979,"date":"2018-03-04T14:14:01","date_gmt":"2018-03-04T20:14:01","guid":{"rendered":"https:\/\/artvallarta.com\/the-magical-mar-2018\/"},"modified":"2018-03-04T14:14:01","modified_gmt":"2018-03-04T20:14:01","slug":"the-magical-mar-2018","status":"publish","type":"post","link":"https:\/\/artvallarta.com\/es\/the-magical-mar-2018\/","title":{"rendered":"The Magical Mar &#8211; 2018"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"49979\" class=\"elementor elementor-49979 elementor-18257\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b10dd87 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"b10dd87\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fde3a51\" data-id=\"fde3a51\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-92c267b elementor-widget elementor-widget-wd_products\" data-id=\"92c267b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wd-products-element\">\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"products elements-grid row wd-products-holder pagination- wd-spacing-30 grid-columns-3 align-items-start\" data-paged=\"1\" data-atts=\"{&quot;element_title&quot;:&quot;&quot;,&quot;title_alignment&quot;:&quot;left&quot;,&quot;query_post_type&quot;:&quot;product&quot;,&quot;post_type&quot;:&quot;product&quot;,&quot;include&quot;:null,&quot;taxonomies&quot;:[&quot;352&quot;],&quot;offset&quot;:&quot;&quot;,&quot;orderby&quot;:&quot;&quot;,&quot;query_type&quot;:&quot;OR&quot;,&quot;order&quot;:null,&quot;meta_key&quot;:null,&quot;exclude&quot;:&quot;&quot;,&quot;shop_tools&quot;:null,&quot;hide_out_of_stock&quot;:&quot;no&quot;,&quot;ajax_recently_viewed&quot;:null,&quot;speed&quot;:null,&quot;slides_per_view&quot;:null,&quot;slides_per_view_tablet&quot;:{&quot;size&quot;:&quot;&quot;},&quot;slides_per_view_mobile&quot;:{&quot;size&quot;:&quot;&quot;},&quot;wrap&quot;:null,&quot;autoplay&quot;:null,&quot;center_mode&quot;:null,&quot;hide_pagination_control&quot;:null,&quot;hide_prev_next_buttons&quot;:null,&quot;scroll_per_page&quot;:null,&quot;layout&quot;:&quot;grid&quot;,&quot;pagination&quot;:&quot;&quot;,&quot;items_per_page&quot;:12,&quot;spacing&quot;:&quot;30&quot;,&quot;columns&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3,&quot;sizes&quot;:[]},&quot;columns_tablet&quot;:{&quot;size&quot;:&quot;&quot;},&quot;columns_mobile&quot;:{&quot;size&quot;:&quot;&quot;},&quot;products_masonry&quot;:&quot;&quot;,&quot;products_different_sizes&quot;:&quot;&quot;,&quot;product_quantity&quot;:&quot;&quot;,&quot;product_hover&quot;:&quot;inherit&quot;,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stretch_product&quot;:null,&quot;stretch_product_tablet&quot;:0,&quot;stretch_product_mobile&quot;:0,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;highlighted_products&quot;:&quot;0&quot;,&quot;products_bordered_grid&quot;:&quot;0&quot;,&quot;products_bordered_grid_style&quot;:null,&quot;products_with_background&quot;:&quot;0&quot;,&quot;products_shadow&quot;:&quot;0&quot;,&quot;products_color_scheme&quot;:&quot;default&quot;,&quot;img_size&quot;:&quot;large&quot;,&quot;img_size_custom&quot;:null,&quot;grid_gallery&quot;:&quot;&quot;,&quot;grid_gallery_control&quot;:null,&quot;grid_gallery_enable_arrows&quot;:null,&quot;ajax_page&quot;:&quot;&quot;,&quot;force_not_ajax&quot;:&quot;no&quot;,&quot;lazy_loading&quot;:&quot;no&quot;,&quot;scroll_carousel_init&quot;:null,&quot;custom_sizes&quot;:false,&quot;elementor&quot;:true}\" data-source=\"shortcode\" data-columns=\"3\" data-grid-gallery=\"\">\n\t\t\n\t\t\n\t\t\t\t\t\t\t\t<div class=\"product-grid-item wd-with-labels product product-no-swatches wd-hover-base wd-hover-with-fade  col-lg-4 col-md-4 col-6 first  type-product post-52825 status-publish outofstock product_cat-exhibition-2018-the-magical-mar-es product_cat-gallery-art product_cat-veronica-rangel-es has-post-thumbnail sold-individually taxable shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"52825\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/artvallarta.com\/es\/producto\/art-piece-1-vr\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rectangular\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img fetchpriority=\"high\" decoding=\"async\" width=\"755\" height=\"1024\" src=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/03\/54798938_368238494026463_3952716156934029312_n-e1554491844955.jpg\" class=\"attachment-large size-large wp-image-52826\" alt=\"\" srcset=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/03\/54798938_368238494026463_3952716156934029312_n-e1554491844955.jpg 1256w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/03\/54798938_368238494026463_3952716156934029312_n-e1554491844955-150x204.jpg 150w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/03\/54798938_368238494026463_3952716156934029312_n-e1554491844955-1200x1628.jpg 1200w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/03\/54798938_368238494026463_3952716156934029312_n-e1554491844955-1000x1357.jpg 1000w\" sizes=\"(max-width: 755px) 100vw, 755px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/artvallarta.com\/es\/compare\/\" data-id=\"15605\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/artvallarta.com\/es\/producto\/art-piece-1-vr\/\">Alma Ola by Veronica Rangel<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">MXN<\/span>6,500.00<\/bdi><\/span><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tWatercolor\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><span><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/artvallarta.com\/es\/lista-de-deseos\/\" data-key=\"f8c8f20654\" data-product-id=\"15605\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>A\u00f1adir a mis favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"https:\/\/artvallarta.com\/es\/producto\/art-piece-1-vr\/\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"52825\" data-product_sku=\"\" aria-label=\"Lee m\u00e1s sobre &ldquo;Alma Ola by Veronica Rangel&rdquo;\" rel=\"nofollow\" data-success_message=\"\"><span>Leer m\u00e1s<\/span><\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/artvallarta.com\/es\/producto\/art-piece-1-vr\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"52825\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"product-grid-item wd-with-labels product product-no-swatches wd-hover-base wd-hover-with-fade  col-lg-4 col-md-4 col-6 type-product post-51868 status-publish last outofstock product_cat-exhibition-2018-the-magical-mar-es product_cat-gallery-art product_cat-martine-sechoy-wolff-es has-post-thumbnail taxable shipping-taxable product-type-simple\" data-loop=\"2\" data-id=\"51868\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/artvallarta.com\/es\/producto\/barque-solaire\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rectangular\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img decoding=\"async\" width=\"678\" height=\"668\" src=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/Barque_edited.jpg\" class=\"attachment-large size-large wp-image-51869\" alt=\"\" srcset=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/Barque_edited.jpg 678w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/Barque_edited-150x148.jpg 150w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/Barque_edited-500x493.jpg 500w\" sizes=\"(max-width: 678px) 100vw, 678px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/artvallarta.com\/es\/compare\/\" data-id=\"21908\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/artvallarta.com\/es\/producto\/barque-solaire\/\">Barque Solaire by Martine Sechoy Wolff<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tArtist: Martine Sechoy Wolff &nbsp; Size: 38cm x 38cm &nbsp; Acrylic &nbsp; Original\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><span><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/artvallarta.com\/es\/lista-de-deseos\/\" data-key=\"f8c8f20654\" data-product-id=\"21908\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>A\u00f1adir a mis favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"https:\/\/artvallarta.com\/es\/producto\/barque-solaire\/\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"51868\" data-product_sku=\"\" aria-label=\"Lee m\u00e1s sobre &ldquo;Barque Solaire by Martine Sechoy Wolff&rdquo;\" rel=\"nofollow\" data-success_message=\"\"><span>Leer m\u00e1s<\/span><\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/artvallarta.com\/es\/producto\/barque-solaire\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"51868\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"product-grid-item wd-with-labels product product-no-swatches wd-hover-base wd-hover-with-fade  col-lg-4 col-md-4 col-6 last  type-product post-51872 status-publish first outofstock product_cat-exhibition-2018-the-magical-mar-es product_cat-gallery-art product_cat-martine-sechoy-wolff-es has-post-thumbnail taxable shipping-taxable product-type-simple\" data-loop=\"3\" data-id=\"51872\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/artvallarta.com\/es\/producto\/bleu-d-azur\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rectangular\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img decoding=\"async\" width=\"645\" height=\"632\" src=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/Bleu-dazur_edited.jpg\" class=\"attachment-large size-large wp-image-51873\" alt=\"\" srcset=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/Bleu-dazur_edited.jpg 645w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/Bleu-dazur_edited-150x147.jpg 150w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/Bleu-dazur_edited-500x490.jpg 500w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/Bleu-dazur_edited-300x294.jpg 300w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/Bleu-dazur_edited-42x42.jpg 42w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/Bleu-dazur_edited-32x32.jpg 32w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/artvallarta.com\/es\/compare\/\" data-id=\"21910\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/artvallarta.com\/es\/producto\/bleu-d-azur\/\">Bleu d Azur by Martine Sechoy Wolff<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tArtist: Martine Sechoy Wolff &nbsp; Size: 28cm x 28cm &nbsp; Acrylic &nbsp; Original\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><span><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/artvallarta.com\/es\/lista-de-deseos\/\" data-key=\"f8c8f20654\" data-product-id=\"21910\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>A\u00f1adir a mis favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"https:\/\/artvallarta.com\/es\/producto\/bleu-d-azur\/\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"51872\" data-product_sku=\"\" aria-label=\"Lee m\u00e1s sobre &ldquo;Bleu d Azur by Martine Sechoy Wolff&rdquo;\" rel=\"nofollow\" data-success_message=\"\"><span>Leer m\u00e1s<\/span><\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/artvallarta.com\/es\/producto\/bleu-d-azur\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"51872\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"product-grid-item product product-no-swatches wd-hover-base wd-hover-with-fade  col-lg-4 col-md-4 col-6 first  type-product post-51825 status-publish instock product_cat-chelo-es product_cat-exhibition-2018-the-magical-mar-es product_cat-gallery-art has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"4\" data-id=\"51825\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/artvallarta.com\/es\/producto\/boca-de-tomatlan-i\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"415\" height=\"410\" src=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/boca.jpg\" class=\"attachment-large size-large wp-image-51826\" alt=\"\" srcset=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/boca.jpg 415w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/boca-150x148.jpg 150w\" sizes=\"(max-width: 415px) 100vw, 415px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/artvallarta.com\/es\/compare\/\" data-id=\"21935\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/artvallarta.com\/es\/producto\/boca-de-tomatlan-i\/\">Boca de Tomatl\u00e1n I by Chelo<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">MXN<\/span>3,200.00<\/bdi><\/span><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tArtist:\u00a0Chelo &nbsp; Size: 11 x 13 3\/4\u00a0inches &nbsp; Arcylic &nbsp; Original\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><span><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/artvallarta.com\/es\/lista-de-deseos\/\" data-key=\"f8c8f20654\" data-product-id=\"21935\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>A\u00f1adir a mis favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/es\/wp-json\/wp\/v2\/posts\/49979?add-to-cart=51825\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"51825\" data-product_sku=\"\" aria-label=\"A\u00f1adir al carrito: &ldquo;Boca de Tomatl\u00e1n I by Chelo&rdquo;\" rel=\"nofollow\" data-success_message=\"\u00abBoca de Tomatl\u00e1n I by Chelo\u00bb se ha a\u00f1adido a tu carrito\" role=\"button\"><span>A\u00f1adir al carrito<\/span><\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/artvallarta.com\/es\/producto\/boca-de-tomatlan-i\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"51825\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"product-grid-item product product-no-swatches wd-hover-base wd-hover-with-fade  col-lg-4 col-md-4 col-6 type-product post-51835 status-publish last instock product_cat-chelo-es product_cat-exhibition-2018-the-magical-mar-es product_cat-gallery-art has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"51835\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/artvallarta.com\/es\/producto\/boca-de-tomatlan-ii\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"416\" height=\"416\" src=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/bocaII.jpg\" class=\"attachment-large size-large wp-image-51836\" alt=\"\" srcset=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/bocaII.jpg 416w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/bocaII-150x150.jpg 150w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/bocaII-300x300.jpg 300w\" sizes=\"(max-width: 416px) 100vw, 416px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/artvallarta.com\/es\/compare\/\" data-id=\"21934\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/artvallarta.com\/es\/producto\/boca-de-tomatlan-ii\/\">Boca de Tomatl\u00e1n II by Chelo<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">MXN<\/span>4,050.00<\/bdi><\/span><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tArtist:\u00a0Chelo &nbsp; Size: 12 x 16\u00a0inches &nbsp; Arcylic &nbsp; Original\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><span><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/artvallarta.com\/es\/lista-de-deseos\/\" data-key=\"f8c8f20654\" data-product-id=\"21934\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>A\u00f1adir a mis favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/es\/wp-json\/wp\/v2\/posts\/49979?add-to-cart=51835\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"51835\" data-product_sku=\"\" aria-label=\"A\u00f1adir al carrito: &ldquo;Boca de Tomatl\u00e1n II by Chelo&rdquo;\" rel=\"nofollow\" data-success_message=\"\u00abBoca de Tomatl\u00e1n II by Chelo\u00bb se ha a\u00f1adido a tu carrito\" role=\"button\"><span>A\u00f1adir al carrito<\/span><\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/artvallarta.com\/es\/producto\/boca-de-tomatlan-ii\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"51835\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"product-grid-item wd-with-labels product product-no-swatches wd-hover-base wd-hover-with-fade  col-lg-4 col-md-4 col-6 last  type-product post-51833 status-publish first outofstock product_cat-bart-pass-es product_cat-exhibition-2018-the-magical-mar-es product_cat-gallery-art has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"6\" data-id=\"51833\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/artvallarta.com\/es\/producto\/breakfast\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rectangular\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"414\" height=\"407\" src=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/breakfast.jpg\" class=\"attachment-large size-large wp-image-51834\" alt=\"\" srcset=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/breakfast.jpg 414w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/breakfast-150x147.jpg 150w\" sizes=\"(max-width: 414px) 100vw, 414px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/artvallarta.com\/es\/compare\/\" data-id=\"21933\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/artvallarta.com\/es\/producto\/breakfast\/\">Breakfast on the beach &#8211; A Plein Air Study by Bart Pass<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">MXN<\/span>16,200.00<\/bdi><\/span><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tArtist: Bart Pass &nbsp; Size: 32 x 40 inches &nbsp; Acrylic &nbsp; Original\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><span><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/artvallarta.com\/es\/lista-de-deseos\/\" data-key=\"f8c8f20654\" data-product-id=\"21933\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>A\u00f1adir a mis favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"https:\/\/artvallarta.com\/es\/producto\/breakfast\/\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"51833\" data-product_sku=\"\" aria-label=\"Lee m\u00e1s sobre &ldquo;Breakfast on the beach - A Plein Air Study by Bart Pass&rdquo;\" rel=\"nofollow\" data-success_message=\"\"><span>Leer m\u00e1s<\/span><\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/artvallarta.com\/es\/producto\/breakfast\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"51833\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"product-grid-item wd-with-labels product product-no-swatches wd-hover-base wd-hover-with-fade  col-lg-4 col-md-4 col-6 first  type-product post-51792 status-publish outofstock product_cat-exhibition-2018-the-magical-mar-es product_cat-gallery-art product_cat-kika-es has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"51792\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/artvallarta.com\/es\/producto\/caballito-de-mar\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rectangular\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"408\" height=\"409\" src=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/CDM.jpg\" class=\"attachment-large size-large wp-image-51793\" alt=\"\" srcset=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/CDM.jpg 408w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/CDM-150x150.jpg 150w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/CDM-300x300.jpg 300w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/CDM-42x42.jpg 42w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/CDM-32x32.jpg 32w\" sizes=\"(max-width: 408px) 100vw, 408px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/artvallarta.com\/es\/compare\/\" data-id=\"21948\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/artvallarta.com\/es\/producto\/caballito-de-mar\/\">Caballito de mar by Kika<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">MXN<\/span>2,800.00<\/bdi><\/span><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tArtist:\u00a0 Kika &nbsp; Size: 19.5 x 16.5 &nbsp; Acrylic &nbsp; Original\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><span><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/artvallarta.com\/es\/lista-de-deseos\/\" data-key=\"f8c8f20654\" data-product-id=\"21948\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>A\u00f1adir a mis favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"https:\/\/artvallarta.com\/es\/producto\/caballito-de-mar\/\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"51792\" data-product_sku=\"\" aria-label=\"Lee m\u00e1s sobre &ldquo;Caballito de mar by Kika&rdquo;\" rel=\"nofollow\" data-success_message=\"\"><span>Leer m\u00e1s<\/span><\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/artvallarta.com\/es\/producto\/caballito-de-mar\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"51792\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"product-grid-item wd-with-labels product product-no-swatches wd-hover-base wd-hover-with-fade  col-lg-4 col-md-4 col-6 type-product post-51856 status-publish last outofstock product_cat-exhibition-2018-the-magical-mar-es product_cat-gallery-art product_cat-martine-sechoy-wolff-es has-post-thumbnail taxable shipping-taxable product-type-simple\" data-loop=\"8\" data-id=\"51856\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/artvallarta.com\/es\/producto\/complicity\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rectangular\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"836\" height=\"960\" src=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/29138736_10155246905399147_1176714332_n.jpg\" class=\"attachment-large size-large wp-image-51857\" alt=\"\" srcset=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/29138736_10155246905399147_1176714332_n.jpg 836w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/29138736_10155246905399147_1176714332_n-150x172.jpg 150w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/29138736_10155246905399147_1176714332_n-500x574.jpg 500w\" sizes=\"(max-width: 836px) 100vw, 836px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/artvallarta.com\/es\/compare\/\" data-id=\"21913\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/artvallarta.com\/es\/producto\/complicity\/\">Complicity by Martine Sechoy Wolff<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tArtist: Martine Sechoy Wolff &nbsp; Size: 70cm x 80cm &nbsp; Acrylic &nbsp; Original\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><span><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/artvallarta.com\/es\/lista-de-deseos\/\" data-key=\"f8c8f20654\" data-product-id=\"21913\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>A\u00f1adir a mis favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"https:\/\/artvallarta.com\/es\/producto\/complicity\/\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"51856\" data-product_sku=\"\" aria-label=\"Lee m\u00e1s sobre &ldquo;Complicity by Martine Sechoy Wolff&rdquo;\" rel=\"nofollow\" data-success_message=\"\"><span>Leer m\u00e1s<\/span><\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/artvallarta.com\/es\/producto\/complicity\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"51856\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"product-grid-item wd-with-labels product product-no-swatches wd-hover-base wd-hover-with-fade  col-lg-4 col-md-4 col-6 last  type-product post-51775 status-publish first outofstock product_cat-angelo-sannasardo-es product_cat-exhibition-2018-the-magical-mar-es product_cat-gallery-art has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"9\" data-id=\"51775\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/artvallarta.com\/es\/producto\/crawford-window\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rectangular\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"698\" height=\"960\" src=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/8.jpg\" class=\"attachment-large size-large wp-image-51776\" alt=\"\" srcset=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/8.jpg 698w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/8-150x206.jpg 150w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/8-500x688.jpg 500w\" sizes=\"(max-width: 698px) 100vw, 698px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/artvallarta.com\/es\/compare\/\" data-id=\"21961\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/artvallarta.com\/es\/producto\/crawford-window\/\">Crawford Window by Angelo Sannasardo<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">MXN<\/span>36,000.00<\/bdi><\/span><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tArtist: Angelo Sannasardo &nbsp; Size: 47 x 39.5 inches &nbsp; Acrylic &nbsp; Original\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><span><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/artvallarta.com\/es\/lista-de-deseos\/\" data-key=\"f8c8f20654\" data-product-id=\"21961\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>A\u00f1adir a mis favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"https:\/\/artvallarta.com\/es\/producto\/crawford-window\/\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"51775\" data-product_sku=\"\" aria-label=\"Lee m\u00e1s sobre &ldquo;Crawford Window by Angelo Sannasardo&rdquo;\" rel=\"nofollow\" data-success_message=\"\"><span>Leer m\u00e1s<\/span><\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/artvallarta.com\/es\/producto\/crawford-window\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"51775\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"product-grid-item wd-with-labels product product-no-swatches wd-hover-base wd-hover-with-fade  col-lg-4 col-md-4 col-6 first  type-product post-51821 status-publish outofstock product_cat-ada-colorina-es product_cat-exhibition-2018-the-magical-mar-es product_cat-gallery-art has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"10\" data-id=\"51821\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/artvallarta.com\/es\/producto\/danza-de-ballenas-ii\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rectangular\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"407\" height=\"410\" src=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/danza.jpg\" class=\"attachment-large size-large wp-image-51822\" alt=\"\" srcset=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/danza.jpg 407w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/danza-150x150.jpg 150w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/danza-298x300.jpg 298w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/danza-42x42.jpg 42w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/danza-32x32.jpg 32w\" sizes=\"(max-width: 407px) 100vw, 407px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/artvallarta.com\/es\/compare\/\" data-id=\"21939\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/artvallarta.com\/es\/producto\/danza-de-ballenas-ii\/\">Danza de ballenas II by Ada Colorina<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">MXN<\/span>14,400.00<\/bdi><\/span><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tArtist:\u00a0Ada Colorina &nbsp; Size: 31.5 x 23.5 inches &nbsp; Acrylic &nbsp; Original\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><span><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/artvallarta.com\/es\/lista-de-deseos\/\" data-key=\"f8c8f20654\" data-product-id=\"21939\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>A\u00f1adir a mis favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"https:\/\/artvallarta.com\/es\/producto\/danza-de-ballenas-ii\/\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"51821\" data-product_sku=\"\" aria-label=\"Lee m\u00e1s sobre &ldquo;Danza de ballenas II by Ada Colorina&rdquo;\" rel=\"nofollow\" data-success_message=\"\"><span>Leer m\u00e1s<\/span><\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/artvallarta.com\/es\/producto\/danza-de-ballenas-ii\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"51821\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"product-grid-item product product-no-swatches wd-hover-base wd-hover-with-fade  col-lg-4 col-md-4 col-6 type-product post-51841 status-publish last instock product_cat-exhibition-2018-the-magical-mar-es product_cat-gallery-art product_cat-tony-collantez-es has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"11\" data-id=\"51841\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/artvallarta.com\/es\/producto\/dolphin\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"476\" height=\"476\" src=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/WhatsApp-Image-2019-09-05-at-2.26.04-PM-1.jpeg\" class=\"attachment-large size-large wp-image-51842\" alt=\"\" srcset=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/WhatsApp-Image-2019-09-05-at-2.26.04-PM-1.jpeg 476w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/WhatsApp-Image-2019-09-05-at-2.26.04-PM-1-150x150.jpeg 150w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/WhatsApp-Image-2019-09-05-at-2.26.04-PM-1-300x300.jpeg 300w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/WhatsApp-Image-2019-09-05-at-2.26.04-PM-1-457x457.jpeg 457w\" sizes=\"(max-width: 476px) 100vw, 476px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/artvallarta.com\/es\/compare\/\" data-id=\"21926\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/artvallarta.com\/es\/producto\/dolphin\/\">Dolphin by Tony Collantez<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">MXN<\/span>16,200.00<\/bdi><\/span><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tArtist:\u00a0Tony Collantez &nbsp; Acrylic &nbsp; Original &nbsp; &nbsp;\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><span><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/artvallarta.com\/es\/lista-de-deseos\/\" data-key=\"f8c8f20654\" data-product-id=\"21926\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>A\u00f1adir a mis favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/es\/wp-json\/wp\/v2\/posts\/49979?add-to-cart=51841\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"51841\" data-product_sku=\"\" aria-label=\"A\u00f1adir al carrito: &ldquo;Dolphin by Tony Collantez&rdquo;\" rel=\"nofollow\" data-success_message=\"\u00abDolphin by Tony Collantez\u00bb se ha a\u00f1adido a tu carrito\" role=\"button\"><span>A\u00f1adir al carrito<\/span><\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/artvallarta.com\/es\/producto\/dolphin\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"51841\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"product-grid-item product product-no-swatches wd-hover-base wd-hover-with-fade  col-lg-4 col-md-4 col-6 last  type-product post-51831 status-publish first instock product_cat-bart-pass-es product_cat-exhibition-2018-the-magical-mar-es product_cat-gallery-art has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\" data-loop=\"12\" data-id=\"51831\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/artvallarta.com\/es\/producto\/early-light\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"414\" height=\"412\" src=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/earlybartpass.jpg\" class=\"attachment-large size-large wp-image-51832\" alt=\"\" srcset=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/earlybartpass.jpg 414w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/earlybartpass-150x150.jpg 150w, https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/08\/earlybartpass-300x300.jpg 300w\" sizes=\"(max-width: 414px) 100vw, 414px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/artvallarta.com\/es\/compare\/\" data-id=\"21932\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/artvallarta.com\/es\/producto\/early-light\/\">Early Light by Bart Pass<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">MXN<\/span>5,400.00<\/bdi><\/span><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tArtist: Bart Pass &nbsp; Size: 16\u00a0x 20 inches &nbsp; Acrylic &nbsp; Original\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><span><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/artvallarta.com\/es\/lista-de-deseos\/\" data-key=\"f8c8f20654\" data-product-id=\"21932\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>A\u00f1adir a mis favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/es\/wp-json\/wp\/v2\/posts\/49979?add-to-cart=51831\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"51831\" data-product_sku=\"\" aria-label=\"A\u00f1adir al carrito: &ldquo;Early Light by Bart Pass&rdquo;\" rel=\"nofollow\" data-success_message=\"\u00abEarly Light by Bart Pass\u00bb se ha a\u00f1adido a tu carrito\" role=\"button\"><span>A\u00f1adir al carrito<\/span><\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/artvallarta.com\/es\/producto\/early-light\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"51831\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\n\t\t\n\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":68,"featured_media":49981,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1059],"tags":[],"class_list":["post-49979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-past-exhibition-events-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Magical Mar - 2018 - Art VallARTa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/artvallarta.com\/es\/the-magical-mar-2018\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Magical Mar - 2018 - Art VallARTa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/artvallarta.com\/es\/the-magical-mar-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Art VallARTa\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/artvallarta\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-04T20:14:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/artvallarta.com\/wp-content\/uploads\/2018\/03\/p01-1-e1554751170612.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"502\" \/>\n\t<meta property=\"og:image:height\" content=\"776\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alan Ross\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alan Ross\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/the-magical-mar-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/the-magical-mar-2018\\\/\"},\"author\":{\"name\":\"Alan Ross\",\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/#\\\/schema\\\/person\\\/4097b1533c82696c6ebae1d45b1fa8b5\"},\"headline\":\"The Magical Mar &#8211; 2018\",\"datePublished\":\"2018-03-04T20:14:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/the-magical-mar-2018\\\/\"},\"wordCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/the-magical-mar-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/artvallarta.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/p01-1-e1554751170612.jpg\",\"articleSection\":[\"Exhibici\u00f3n\\\/Eventos pasados\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/the-magical-mar-2018\\\/\",\"url\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/the-magical-mar-2018\\\/\",\"name\":\"The Magical Mar - 2018 - Art VallARTa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/the-magical-mar-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/the-magical-mar-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/artvallarta.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/p01-1-e1554751170612.jpg\",\"datePublished\":\"2018-03-04T20:14:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/the-magical-mar-2018\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/artvallarta.com\\\/es\\\/the-magical-mar-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/the-magical-mar-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/artvallarta.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/p01-1-e1554751170612.jpg\",\"contentUrl\":\"https:\\\/\\\/artvallarta.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/p01-1-e1554751170612.jpg\",\"width\":502,\"height\":776},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/the-magical-mar-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagina principal\",\"item\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/art-vallarta-puerto-vallarta-mexico-home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Magical Mar &#8211; 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/\",\"name\":\"Art VallARTa\",\"description\":\"Art VallARTa\",\"publisher\":{\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/#organization\",\"name\":\"Art VallARTa\",\"url\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/artvallarta.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/51835738_615449708895218_133232196214325248_n.jpg\",\"contentUrl\":\"https:\\\/\\\/artvallarta.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/51835738_615449708895218_133232196214325248_n.jpg\",\"width\":2048,\"height\":1466,\"caption\":\"Art VallARTa\"},\"image\":{\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/artvallarta\",\"http:\\\/\\\/www.instagram.com\\\/artvallarta\",\"http:\\\/\\\/www.pinterest\\\/artvallarta\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCOqDy2Oyk7EU4tz3S2Gl7kQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/#\\\/schema\\\/person\\\/4097b1533c82696c6ebae1d45b1fa8b5\",\"name\":\"Alan Ross\",\"url\":\"https:\\\/\\\/artvallarta.com\\\/es\\\/author\\\/alanworldtvl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Magical Mar - 2018 - Art VallARTa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/artvallarta.com\/es\/the-magical-mar-2018\/","og_locale":"es_ES","og_type":"article","og_title":"The Magical Mar - 2018 - Art VallARTa","og_url":"https:\/\/artvallarta.com\/es\/the-magical-mar-2018\/","og_site_name":"Art VallARTa","article_publisher":"http:\/\/www.facebook.com\/artvallarta","article_published_time":"2018-03-04T20:14:01+00:00","og_image":[{"width":502,"height":776,"url":"https:\/\/artvallarta.com\/wp-content\/uploads\/2018\/03\/p01-1-e1554751170612.jpg","type":"image\/jpeg"}],"author":"Alan Ross","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Alan Ross","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/artvallarta.com\/es\/the-magical-mar-2018\/#article","isPartOf":{"@id":"https:\/\/artvallarta.com\/es\/the-magical-mar-2018\/"},"author":{"name":"Alan Ross","@id":"https:\/\/artvallarta.com\/es\/#\/schema\/person\/4097b1533c82696c6ebae1d45b1fa8b5"},"headline":"The Magical Mar &#8211; 2018","datePublished":"2018-03-04T20:14:01+00:00","mainEntityOfPage":{"@id":"https:\/\/artvallarta.com\/es\/the-magical-mar-2018\/"},"wordCount":4,"publisher":{"@id":"https:\/\/artvallarta.com\/es\/#organization"},"image":{"@id":"https:\/\/artvallarta.com\/es\/the-magical-mar-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/artvallarta.com\/wp-content\/uploads\/2018\/03\/p01-1-e1554751170612.jpg","articleSection":["Exhibici\u00f3n\/Eventos pasados"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/artvallarta.com\/es\/the-magical-mar-2018\/","url":"https:\/\/artvallarta.com\/es\/the-magical-mar-2018\/","name":"The Magical Mar - 2018 - Art VallARTa","isPartOf":{"@id":"https:\/\/artvallarta.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/artvallarta.com\/es\/the-magical-mar-2018\/#primaryimage"},"image":{"@id":"https:\/\/artvallarta.com\/es\/the-magical-mar-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/artvallarta.com\/wp-content\/uploads\/2018\/03\/p01-1-e1554751170612.jpg","datePublished":"2018-03-04T20:14:01+00:00","breadcrumb":{"@id":"https:\/\/artvallarta.com\/es\/the-magical-mar-2018\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/artvallarta.com\/es\/the-magical-mar-2018\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/artvallarta.com\/es\/the-magical-mar-2018\/#primaryimage","url":"https:\/\/artvallarta.com\/wp-content\/uploads\/2018\/03\/p01-1-e1554751170612.jpg","contentUrl":"https:\/\/artvallarta.com\/wp-content\/uploads\/2018\/03\/p01-1-e1554751170612.jpg","width":502,"height":776},{"@type":"BreadcrumbList","@id":"https:\/\/artvallarta.com\/es\/the-magical-mar-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagina principal","item":"https:\/\/artvallarta.com\/es\/art-vallarta-puerto-vallarta-mexico-home\/"},{"@type":"ListItem","position":2,"name":"The Magical Mar &#8211; 2018"}]},{"@type":"WebSite","@id":"https:\/\/artvallarta.com\/es\/#website","url":"https:\/\/artvallarta.com\/es\/","name":"Art VallARTa","description":"Art VallARTa","publisher":{"@id":"https:\/\/artvallarta.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/artvallarta.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/artvallarta.com\/es\/#organization","name":"Art VallARTa","url":"https:\/\/artvallarta.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/artvallarta.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/02\/51835738_615449708895218_133232196214325248_n.jpg","contentUrl":"https:\/\/artvallarta.com\/wp-content\/uploads\/2019\/02\/51835738_615449708895218_133232196214325248_n.jpg","width":2048,"height":1466,"caption":"Art VallARTa"},"image":{"@id":"https:\/\/artvallarta.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/artvallarta","http:\/\/www.instagram.com\/artvallarta","http:\/\/www.pinterest\/artvallarta","https:\/\/www.youtube.com\/channel\/UCOqDy2Oyk7EU4tz3S2Gl7kQ"]},{"@type":"Person","@id":"https:\/\/artvallarta.com\/es\/#\/schema\/person\/4097b1533c82696c6ebae1d45b1fa8b5","name":"Alan Ross","url":"https:\/\/artvallarta.com\/es\/author\/alanworldtvl\/"}]}},"_links":{"self":[{"href":"https:\/\/artvallarta.com\/es\/wp-json\/wp\/v2\/posts\/49979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artvallarta.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/artvallarta.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/artvallarta.com\/es\/wp-json\/wp\/v2\/users\/68"}],"replies":[{"embeddable":true,"href":"https:\/\/artvallarta.com\/es\/wp-json\/wp\/v2\/comments?post=49979"}],"version-history":[{"count":0,"href":"https:\/\/artvallarta.com\/es\/wp-json\/wp\/v2\/posts\/49979\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artvallarta.com\/es\/wp-json\/wp\/v2\/media\/49981"}],"wp:attachment":[{"href":"https:\/\/artvallarta.com\/es\/wp-json\/wp\/v2\/media?parent=49979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/artvallarta.com\/es\/wp-json\/wp\/v2\/categories?post=49979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/artvallarta.com\/es\/wp-json\/wp\/v2\/tags?post=49979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}